{"id":1278,"date":"2024-11-23T20:26:01","date_gmt":"2024-11-23T19:26:01","guid":{"rendered":"https:\/\/www.picdrop.com\/?p=1278"},"modified":"2026-06-19T11:20:03","modified_gmt":"2026-06-19T09:20:03","slug":"better-do-postponing-loses","status":"publish","type":"post","link":"https:\/\/www.picdrop.com\/web\/de\/artikel\/better-do-postponing-loses","title":{"rendered":"Besser machen Wer aufschiebt, verliert!"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1278\" class=\"elementor elementor-1278 elementor-335\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d56f96f e-flex e-con-boxed e-con e-parent\" data-id=\"d56f96f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c8d860 elementor-widget elementor-widget-image\" data-id=\"5c8d860\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"420\" src=\"https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/istock-1362894903-kopie.jpg\" class=\"attachment-large size-large wp-image-1279\" alt=\"Eine Person in einem rot-wei\u00df gestreiften Hemd steht vor einem gelben Hintergrund. Ihr Kopf wird durch eine gro\u00dfe, chaotische schwarze Kritzelei ersetzt, die Verwirrung oder geistige \u00dcberforderung symbolisiert.\" srcset=\"https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/istock-1362894903-kopie.jpg 1200w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/istock-1362894903-kopie-960x504.jpg 960w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/istock-1362894903-kopie-768x403.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a92657b elementor-widget elementor-widget-text-editor\" data-id=\"a92657b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Selbst\u00e4ndig sein bedeutet, alles selbst zu machen und das st\u00e4ndig \u2013 das kennst du? Freiberufler wie Fotografinnen und Fotografen legen ihren Fokus dabei gerne auf naheliegende Aufgaben, die ein Job mit sich bringt: Fotografieren, Bildauswahl, Bildbearbeitung. Andere Aufgaben, die wichtig f\u00fcr die Selbst\u00e4ndigkeit sind, f\u00fcr die es aber gerade keine Deadline gibt, werden gerne immer weiter verschoben oder gar nicht erledigt. Und manchmal startet der Arbeitstag auch erst am Nachmittag, denn im Caf\u00e9 mit Freunden zu sitzen geh\u00f6rt quasi zur Selbstst\u00e4ndigkeit dazu. Sonst k\u00f6nnte man schlie\u00dflich auch einen \u201enine to five-Job\u201c annehmen. Dabei kannst du viel erfolgreicher sein, wenn du auch die nicht kundenspezifischen Aufgaben priorisierst und angehst.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d586435 elementor-widget elementor-widget-heading\" data-id=\"d586435\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sei Unternehmer, mit allem, was dazu z\u00e4hlt<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83244df elementor-widget elementor-widget-text-editor\" data-id=\"83244df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Hier \u00fcber Prokrastination zu reden, w\u00e4re total \u00fcberzogen. Das w\u00e4re schon pathologische Aufschieberitis und somit nicht nur therapiebed\u00fcrftig, sondern auch ein gro\u00dfes Risiko f\u00fcr deinen Job und deine Selbst\u00e4ndigkeit. Als BerufsfotografIn kannst du dir solche Fehleinsch\u00e4tzungen oder blinde Flecken einfach nicht leisten. Trotzdem habe ich manchmal das Gef\u00fchl, dass manche Leute ihren Erfolg (unabsichtlich) aufs Spiel setzen, weil sie falsche oder gar keine Priorit\u00e4ten setzen. Du auch?<\/p><p>In Gespr\u00e4chen dreht sich oft alles um die Menge und die Qualit\u00e4t der Jobs. Immer wieder h\u00f6re ich, dass es an beidem fehlt. Schnell kommt dann auch das Thema Kundenakquise auf. Oft frustrierend ist, dass es kaum Aktivit\u00e4ten in dieser Richtung gibt oder nie nennenswerte und planvolle Aktionen stattgefunden haben. Erstaunlich, wie sich die Betreffenden trotz dieser Vers\u00e4umnisse am Markt behaupten \u2013 bis jetzt.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d93805 elementor-widget elementor-widget-heading\" data-id=\"7d93805\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u00dcberliste deine Wahrnehmung und erweitere dein Blickfeld<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f89fb6 elementor-widget elementor-widget-text-editor\" data-id=\"4f89fb6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wie entscheidest du eigentlich, was du tust und welche Art von Arbeit du im Berufsalltag erledigen willst? Wir stehen morgens auf, super, kein Termin, also geht\u2019s erst mal mit dem Kaffee an den Laptop. Obwohl wir eine lange Liste (auch wenn sie nur im Kopf ist) mit Aufgaben haben, w\u00e4hlen wir oft die naheliegende Aufgabe. Die, die direkt vor uns liegt, bei der wir nicht viel planen oder nachdenken m\u00fcssen. Wahrscheinlich etwas, was wir gerne machen und was uns leicht f\u00e4llt. Aufgaben, die neu f\u00fcr uns sind, die wir selten erledigen oder in denen uns Wissen und Praxis fehlen, rutschen ziemlich sicher auf die hinteren R\u00e4nge der To-do-Liste. Dazu z\u00e4hlen leider oft die wichtigsten Themen wie Kundenpflege und Kundengewinnung. Und so schieben wir wichtige Aufgaben von Woche zu Woche und werden immer unzufriedener.<\/p><p>Unsere selektive Wahrnehmung sorgt daf\u00fcr, dass wir eher das sehen, was wir sehen wollen, und dadurch die Aufgaben vorziehen, die in unserem Blickfeld liegen. Ein gut funktionierender Verdr\u00e4ngungsmechanismus \u2013 wider besseres Wissen. Wenn schlie\u00dflich doch ein umsetzbarer Plan vorliegt, ist die Motivation hoch, denn das Wissen, dass diese Dinge erfolgsrelevant sind und etwas bewirken, war oft schon da. Aber das Machen gelingt dir erst mit einem Plan, dessen Umsetzung positive Wirkung f\u00fcr deinen Arbeitsbereich bereith\u00e4lt. Kein psychologischer Trick, nur ein bisschen Selbst\u00fcberlistung.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca8f7bf elementor-widget elementor-widget-heading\" data-id=\"ca8f7bf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unterscheide wichtig und dringend<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53f5b5a elementor-widget elementor-widget-text-editor\" data-id=\"53f5b5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Was hilft dir bei der Aufschieberitis? Mit einem Arbeitstagebuch zur Zeiterfassung kannst du dich gut selbst beobachten und den ben\u00f6tigten Aufwand analysieren. Aufzuschreiben, wann gearbeitet wird und welche Aufgaben mit welchem Zeitumfang erledigt werden, hilft, sich \u00fcber die eigene Effizienz im Job bewusst zu sein. Bei den vielen Aufgaben, die t\u00e4glich auf unserer Arbeitsliste stehen, n\u00fctzt eine Einordnung: Was ist wichtig und was ist dringend? Ein t\u00e4gliches Screening deiner Aufgaben, um sie priorisiert abzuarbeiten. Dabei sind dringende Aufgaben nicht unbedingt wichtig, aber an eine Deadline gebunden, wie zum Beispiel die R\u00fcckgabe von Rent-Equipment. Und wichtige Aufgaben sind selten dringend, wie beispielsweise Marketing oder die Aktualisierung deines Portfolios. Allerdings werden wichtige Aufgaben irgendwann dringend, etwa wenn Akquisitions-Vers\u00e4umnisse dazu f\u00fchren, dass zu wenig Jobs da sind. Unangenehm, denn pl\u00f6tzlich sind diese Aufgaben wichtig und dringend zugleich.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d4fe74 elementor-widget elementor-widget-heading\" data-id=\"3d4fe74\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wissen ist gut, machen ist besser<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-255ee69 elementor-widget elementor-widget-text-editor\" data-id=\"255ee69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Soweit muss es nicht kommen. Suche dir Aufgaben, auf deren Erledigung du stolz sein kannst, kleine Challenges in deinem t\u00e4glichen Workflow. Behalte dabei deinen Fokus und frag dich, ob es deinen Zielen hilft, dein Netzwerk verbessert oder deinen Horizont erweitert. Such dir die Aufgaben, die einen positiven und nachhaltigen Effekt auf dein Unternehmen haben. Tr\u00f6stlich: Aufschieberitis ist normal, laut einer Studie der Universit\u00e4t M\u00fcnster unter 98 % der Befragten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e98800 elementor-widget elementor-widget-heading\" data-id=\"1e98800\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Recap<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35a53a1 elementor-widget elementor-widget-text-editor\" data-id=\"35a53a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Priorisiere auch nicht Kundengebundenen Aufgaben<\/li><li>Fordere dich selbst und erledige nicht nur Naheliegendes<\/li><li>Mach dir einen Plan mit Aufgaben, die auf dein Foto-Business einzahlen<\/li><li>F\u00fchre ein Arbeitstagebuch, erfasse Zeiten und Aufgaben, die du erledigst<\/li><li>Unterscheide wichtig und dringend<\/li><li>Setze Priorit\u00e4ten und halte dich daran (so gut wie m\u00f6glich)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9264dbf e-flex e-con-boxed e-con e-parent\" data-id=\"9264dbf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-997db0a elementor-widget elementor-widget-text-editor\" data-id=\"997db0a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>Von Silke G\u00fcldner<\/b><\/p><p>Silke G\u00fcldner ist Coach und Consultant f\u00fcr Fotografinnen und Fotografen und Kreative.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1edfd5 elementor-widget elementor-widget-image\" data-id=\"a1edfd5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"720\" height=\"720\" src=\"https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/img_5332-720x720.jpg\" class=\"attachment-medium size-medium wp-image-1303\" alt=\"Eine Frau mit langen grauen Haaren l\u00e4chelt sanft und st\u00fctzt ihr Kinn auf die Hand. Sie befindet sich in einem modernen Raum mit bunten Postern an der Wand hinter ihr.\" srcset=\"https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/img_5332-720x720.jpg 720w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/img_5332-1080x1080.jpg 1080w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/img_5332-540x540.jpg 540w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/img_5332-768x768.jpg 768w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/img_5332.jpg 1399w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8933162 e-flex e-con-boxed e-con e-parent\" data-id=\"8933162\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Welche Aufgaben einen nachhaltigen Impact auf dein Foto-Business haben und warum Aufschieben keine L\u00f6sung ist<\/p>\n","protected":false},"author":28,"featured_media":1280,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[108],"tags":[],"class_list":["post-1278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fotografie-business"],"_links":{"self":[{"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/posts\/1278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/comments?post=1278"}],"version-history":[{"count":1,"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/posts\/1278\/revisions"}],"predecessor-version":[{"id":5351,"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/posts\/1278\/revisions\/5351"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/media\/1280"}],"wp:attachment":[{"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/media?parent=1278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/categories?post=1278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/tags?post=1278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}