{"id":3623,"date":"2026-03-18T09:15:41","date_gmt":"2026-03-18T09:15:41","guid":{"rendered":"https:\/\/www.picdrop.com\/web?post_type=faq&#038;p=3623"},"modified":"2026-03-18T09:20:06","modified_gmt":"2026-03-18T09:20:06","slug":"content-suche","status":"publish","type":"faq","link":"https:\/\/www.picdrop.com\/web\/de\/faq\/content-suche","title":{"rendered":"Content-Suche"},"content":{"rendered":"\n<p><strong>Was ist die Content-Suche in picdrop?<\/strong><\/p>\n\n\n\n<p>Die Content-Suche ist unsere neue KI-gest\u00fctzte Suchfunktion in picdrop und sie hilft dir dabei, Bilder in deinem Account super schnell \u00fcber Inhalte und Bedeutungen zu finden \u2013 nicht nur \u00fcber Dateinamen und Galerien.<\/p>\n\n\n\n<p>Die Content-Suche ist optional und standardm\u00e4\u00dfig deaktiviert und steht ausschlie\u00dflich im Business-Tarif zur Verf\u00fcgung.<\/p>\n\n\n\n<p><strong>Wie kann ich die Content-Suche f\u00fcr meinen Account aktivieren?<\/strong><\/p>\n\n\n\n<p>Sofern du einen Business-Tarif hast, musst du lediglich deine Kontoeinstellungen \u00f6ffnen und in den <a href=\"https:\/\/www.picdrop.com\/user\/settings#content-search\">Bereich Content-Suche<\/a> wechseln. Dort kannst du die Funktion \u00fcber den Schalter \u201eContent-Suche aktivieren\u201c einschalten.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1574\" height=\"1080\" src=\"https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/\/Kontoeinstellungen_Content_Suche_DE-1-1574x1080.png\" alt=\"\" class=\"wp-image-3640\" srcset=\"https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Kontoeinstellungen_Content_Suche_DE-1-1574x1080.png 1574w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Kontoeinstellungen_Content_Suche_DE-1-1049x720.png 1049w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Kontoeinstellungen_Content_Suche_DE-1-787x540.png 787w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Kontoeinstellungen_Content_Suche_DE-1-768x527.png 768w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Kontoeinstellungen_Content_Suche_DE-1-1536x1054.png 1536w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Kontoeinstellungen_Content_Suche_DE-1-2048x1405.png 2048w\" sizes=\"(max-width: 1574px) 100vw, 1574px\" \/><\/figure>\n\n\n\n<p><strong>Was genau passiert mit meinen Daten, wenn ich die Content Suche in picdrop nutze?<\/strong><\/p>\n\n\n\n<p>Nach der Aktivierung der Content Suche in deinen Kontoeinstellung beginnt automatisch die Indexierung aller Bilder in deinem Account. Dabei analysiert ein Modell, was auf deinen Bildern zu sehen ist \u2013 zum Beispiel Personen oder Objekte. Dieser sichtbare Inhalt wird in eine mathematische Beschreibung \u00fcbersetzt, damit die Bilder sp\u00e4ter schnell und gezielt durchsucht werden k\u00f6nnen.<\/p>\n\n\n\n<p>Wichtig: Selbstverst\u00e4ndlich werden alle Daten sicher und EU-\/DSGVO-konform verarbeitet. Die Analyse der Bildinhalte erfolgt ausschlie\u00dflich auf EU-Servern, die von picdrop kontrolliert werden. Deine Daten, Bildinhalte und Suchanfragen werden nicht verwendet, um KI-Modelle zu trainieren oder weiterzuentwickeln. Weitere Infos dazu findest du auch in unserer <a href=\"https:\/\/www.picdrop.com\/web\/de\/privacy\">Datenschutzerkl\u00e4rung.<\/a><\/p>\n\n\n\n<p><strong>Nutzung der Content Suche:<\/strong><\/p>\n\n\n\n<p>Sobald du die Content Suche f\u00fcr deinen Account aktiviert hast und die Indexierung deiner Daten abgeschlossen ist, kannst du deinen Account mit der Content Suche durchsuchen.<\/p>\n\n\n\n<p>Das geht ganz einfach mit einem Klick auf das Lupen-Symbol in der Leiste am oberen rechten Bildschirmrand. Aktiviere hier noch die Content-Suche f\u00fcr deinen Suchvorgang und w\u00e4hle die Ergebnisgenauigkeit aus.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1664\" height=\"538\" src=\"https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Suchdialog_Content_Suche_DE.png\" alt=\"\" class=\"wp-image-3643\" srcset=\"https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Suchdialog_Content_Suche_DE.png 1664w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Suchdialog_Content_Suche_DE-1280x414.png 1280w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Suchdialog_Content_Suche_DE-960x310.png 960w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Suchdialog_Content_Suche_DE-768x248.png 768w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Suchdialog_Content_Suche_DE-1536x497.png 1536w\" sizes=\"(max-width: 1664px) 100vw, 1664px\" \/><\/figure>\n\n\n\n<p>Gib einfach einen Suchbegriff ein und die Content Suche wird diesen mit den gespeicherten Bildinformationen verglichen und dir im Anschluss passende Bilder anzeigen.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1670\" height=\"924\" src=\"https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Beispielsuche_Content_Suche_DE.png\" alt=\"\" class=\"wp-image-3646\" srcset=\"https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Beispielsuche_Content_Suche_DE.png 1670w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Beispielsuche_Content_Suche_DE-1280x708.png 1280w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Beispielsuche_Content_Suche_DE-960x531.png 960w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Beispielsuche_Content_Suche_DE-768x425.png 768w, https:\/\/www.picdrop.com\/web\/wp-content\/uploads\/Beispielsuche_Content_Suche_DE-1536x850.png 1536w\" sizes=\"(max-width: 1670px) 100vw, 1670px\" \/><\/figure>\n\n\n\n<p>Hier noch ein paar kurze Hinweise:<\/p>\n\n\n\n<p>Die Ergebnisgenauigkeit legt fest, wie \u00e4hnlich der erkannte Bildinhalt deinem Suchbegriff sein muss, damit ein Bild in den Ergebnissen erscheint. Bei niedriger Ergebnisgenauigkeit werden auch Bilder angezeigt, deren Inhalt deinem Suchbegriff nur entfernt \u00e4hneln. Bei hoher Ergebnisgenauigkeit werden dagegen nur Bilder angezeigt, deren erkannter Inhalt sehr nah an deinem Suchbegriff liegt. EXIF- und IPTC-Daten werden in der Content Suche nicht ber\u00fccksichtigt.<\/p>\n\n\n\n<p><strong>Ich m\u00f6chte die Content Suche in meinem Account nicht mehr nutzen, wie kann ich sie deaktivieren?<\/strong><\/p>\n\n\n\n<p>Du kannst die Content Suche f\u00fcr deinen Account jederzeit wieder ausschalten, indem du in deine Kontoeinstellungen gehst und im <a href=\"https:\/\/www.picdrop.com\/user\/settings#content-search\">Bereich Content-Suche<\/a> den Schalter \u201eContent-Suche aktivieren\u201c wieder deaktivierst. Wenn du die Content Suche f\u00fcr deinen Account deaktivierst, l\u00f6schen wir alle bei der Indexierung erzeugten Daten nach 30 Tagen automatisch.<\/p>\n","protected":false},"author":20,"template":"","faq-category":[88],"class_list":["post-3623","faq","type-faq","status-publish","hentry","faq-category-business"],"_links":{"self":[{"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/faq\/3623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/faq"}],"about":[{"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/types\/faq"}],"author":[{"embeddable":true,"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/users\/20"}],"wp:attachment":[{"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/media?parent=3623"}],"wp:term":[{"taxonomy":"faq-category","embeddable":true,"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/faq-category?post=3623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}