{"id":1651,"date":"2024-12-09T20:39:09","date_gmt":"2024-12-09T19:39:09","guid":{"rendered":"https:\/\/www.picdrop.com\/?post_type=faq&#038;p=1651"},"modified":"2025-06-25T11:02:27","modified_gmt":"2025-06-25T11:02:27","slug":"kann-ich-picdrop-auf-meiner-website-einbinden","status":"publish","type":"faq","link":"https:\/\/www.picdrop.com\/web\/de\/faq\/kann-ich-picdrop-auf-meiner-website-einbinden","title":{"rendered":"Kann ich picdrop auf meiner Website einbinden?"},"content":{"rendered":"\n<div style=\"height:10px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Web-Weiterleitung: deine picdrop-Galerien unter deiner Domain<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Mit der\u00a0<a href=\"https:\/\/www.picdrop.com\/user\/settings#web-forwarder\">Web-Weiterleitung<\/a>\u00a0kannst du picdrop unter deiner eigenen Domain laufen lassen, damit deine Kunden initial deine Domain sehen und anschlie\u00dfend zu picdrop weitergeleitet werden. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn du bereits bei picdrop angemeldet bist, findest du\u00a0<a href=\"https:\/\/www.picdrop.com\/user\/settings#web-forwarder\">hier die Installationsdateien<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"author":18,"template":"","faq-category":[74],"class_list":["post-1651","faq","type-faq","status-publish","hentry","faq-category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/faq\/1651","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/faq"}],"about":[{"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/types\/faq"}],"author":[{"embeddable":true,"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/users\/18"}],"wp:attachment":[{"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/media?parent=1651"}],"wp:term":[{"taxonomy":"faq-category","embeddable":true,"href":"https:\/\/www.picdrop.com\/web\/de\/wp-json\/wp\/v2\/faq-category?post=1651"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}